{"id":89301,"date":"2024-02-22T13:37:27","date_gmt":"2023-12-19T05:57:45","guid":{"rendered":"https:\/\/www.mtggrade.com\/cartes\/1071193\/"},"modified":"2024-04-12T15:45:44","modified_gmt":"2024-04-12T13:45:44","slug":"1071193","status":"publish","type":"cartes_cpt","link":"https:\/\/www.mtggrade.com\/en\/cardpage\/1071193\/","title":{"rendered":"1071193"},"content":{"rendered":"<p>Grolem | Fossile<\/p>\n","protected":false},"template":"","class_list":["post-89301","cartes_cpt","type-cartes_cpt","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Certification n\u00b01071193 | MTG Grade<\/title>\n<meta name=\"description\" content=\"Grolem | Fossile\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mtggrade.com\/en\/cardpage\/1071193\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Certification n\u00b01071193 | MTG Grade\" \/>\n<meta property=\"og:description\" content=\"Grolem | Fossile\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mtggrade.com\/en\/cardpage\/1071193\/\" \/>\n<meta property=\"og:site_name\" content=\"MTG Grade\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mtggrade\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-12T13:45:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mtggrade.com\/wp-content\/uploads\/2024\/02\/MTG_GRADE-couverture_facebook-1.2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"843\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mtggrade\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/cardpage\\\/1071193\\\/\",\"url\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/cardpage\\\/1071193\\\/\",\"name\":\"Certification n\u00b01071193 | MTG Grade\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/#website\"},\"datePublished\":\"2023-12-19T05:57:45+00:00\",\"dateModified\":\"2024-04-12T13:45:44+00:00\",\"description\":\"Grolem | Fossile\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/cardpage\\\/1071193\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/cardpage\\\/1071193\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/cardpage\\\/1071193\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartes\",\"item\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/cardpage\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1071193\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/\",\"name\":\"MTG Grade\",\"description\":\"Grading of Pok\u00e9mon, Magic, Dragon Ball, Locarna... cards\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/#organization\",\"name\":\"MTG Grade\",\"url\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mtggrade.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/MTG_GRADE-logo_black.svg\",\"contentUrl\":\"https:\\\/\\\/www.mtggrade.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/MTG_GRADE-logo_black.svg\",\"caption\":\"MTG Grade\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mtggrade.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mtggrade\",\"https:\\\/\\\/x.com\\\/mtggrade\",\"https:\\\/\\\/www.instagram.com\\\/mtggradeoff\\\/?hl=fr\",\"https:\\\/\\\/www.tiktok.com\\\/@mtggrade\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC_SBWGrDqDEd0xjDTdQ9wQQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Certification n\u00b01071193 | MTG Grade","description":"Grolem | Fossile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mtggrade.com\/en\/cardpage\/1071193\/","og_locale":"en_US","og_type":"article","og_title":"Certification n\u00b01071193 | MTG Grade","og_description":"Grolem | Fossile","og_url":"https:\/\/www.mtggrade.com\/en\/cardpage\/1071193\/","og_site_name":"MTG Grade","article_publisher":"https:\/\/www.facebook.com\/mtggrade","article_modified_time":"2024-04-12T13:45:44+00:00","og_image":[{"width":1920,"height":843,"url":"https:\/\/www.mtggrade.com\/wp-content\/uploads\/2024\/02\/MTG_GRADE-couverture_facebook-1.2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@mtggrade","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mtggrade.com\/en\/cardpage\/1071193\/","url":"https:\/\/www.mtggrade.com\/en\/cardpage\/1071193\/","name":"Certification n\u00b01071193 | MTG Grade","isPartOf":{"@id":"https:\/\/www.mtggrade.com\/en\/#website"},"datePublished":"2023-12-19T05:57:45+00:00","dateModified":"2024-04-12T13:45:44+00:00","description":"Grolem | Fossile","breadcrumb":{"@id":"https:\/\/www.mtggrade.com\/en\/cardpage\/1071193\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mtggrade.com\/en\/cardpage\/1071193\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mtggrade.com\/en\/cardpage\/1071193\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.mtggrade.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Cartes","item":"https:\/\/www.mtggrade.com\/en\/cardpage\/"},{"@type":"ListItem","position":3,"name":"1071193"}]},{"@type":"WebSite","@id":"https:\/\/www.mtggrade.com\/en\/#website","url":"https:\/\/www.mtggrade.com\/en\/","name":"MTG Grade","description":"Grading of Pok\u00e9mon, Magic, Dragon Ball, Locarna... cards","publisher":{"@id":"https:\/\/www.mtggrade.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mtggrade.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.mtggrade.com\/en\/#organization","name":"MTG Grade","url":"https:\/\/www.mtggrade.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mtggrade.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.mtggrade.com\/wp-content\/uploads\/2023\/11\/MTG_GRADE-logo_black.svg","contentUrl":"https:\/\/www.mtggrade.com\/wp-content\/uploads\/2023\/11\/MTG_GRADE-logo_black.svg","caption":"MTG Grade"},"image":{"@id":"https:\/\/www.mtggrade.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mtggrade","https:\/\/x.com\/mtggrade","https:\/\/www.instagram.com\/mtggradeoff\/?hl=fr","https:\/\/www.tiktok.com\/@mtggrade","https:\/\/www.youtube.com\/channel\/UC_SBWGrDqDEd0xjDTdQ9wQQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.mtggrade.com\/en\/wp-json\/wp\/v2\/cartes_cpt\/89301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mtggrade.com\/en\/wp-json\/wp\/v2\/cartes_cpt"}],"about":[{"href":"https:\/\/www.mtggrade.com\/en\/wp-json\/wp\/v2\/types\/cartes_cpt"}],"wp:attachment":[{"href":"https:\/\/www.mtggrade.com\/en\/wp-json\/wp\/v2\/media?parent=89301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}